{"id":104,"date":"2010-08-11T12:32:59","date_gmt":"2010-08-11T10:32:59","guid":{"rendered":"http:\/\/www.aquatonic-rennes.com\/"},"modified":"2026-05-13T14:05:46","modified_gmt":"2026-05-13T12:05:46","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/www.aquatonic.fr\/rennes\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"<p>Vous \u00eates actuellement connect\u00e9 au site<strong> aquatonic.fr\/rennes<\/strong>. L&rsquo;utilisateur ayant acc\u00e8s \u00e0 ce site s&rsquo;engage \u00e0 se conformer aux pr\u00e9sentes conditions d&rsquo;utilisation.<\/p>\n<h2>Information \u00e9diteur et h\u00e9bergeur :<\/h2>\n<p>Ce site est \u00e9dit\u00e9 par : LES THERMES MARINS DE SAINT MALO, Soci\u00e9t\u00e9 par actions simplifi\u00e9e au capital de 1 000 000 Euros, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s sous le N\u00b0 RCS SAINT MALO B895 780 245.<\/p>\n<p><strong>Si\u00e8ge social<\/strong><br \/>\nLes Thermes Marins de Saint-Malo<br \/>\nGrande Plage du Sillon BP 32<br \/>\n35 401 SAINT-MALO<br \/>\nN\u00b0 SIRET : 895 780 245 000 26<br \/>\nT\u00e9l : 02 99 40 75 75<\/p>\n<p><strong>Direction G\u00e9n\u00e9rale Internet<\/strong><br \/>\nLes Thermes Marins de Saint-Malo<br \/>\nGrande Plage du Sillon BP 32<br \/>\n35 401 SAINT-MALO<\/p>\n<p><strong>H\u00e9bergeur<br \/>\n<\/strong>Kinsta WordPress Hosting<br \/>\nUnit 22 Bulrushes Business Park<br \/>\nCoombe Hill Road<br \/>\nEast Grinstead<br \/>\nWest SussexRH194LZ, UK<br \/>\ndmca@kinsta.com<\/p>\n<h2>Validit\u00e9 du formulaire de r\u00e9servation :<\/h2>\n<p>L&rsquo;utilisateur de ce site Internet est inform\u00e9 que le formulaire de pr\u00e9-r\u00e9servation ne correspond pas \u00e0 une r\u00e9servation avec paiement en ligne, un contact ult\u00e9rieur et par une voie de communication au choix de l&rsquo;internaute (e-mail, t\u00e9l\u00e9phone ou fax) sera r\u00e9alis\u00e9 afin de lui adresser une proposition personnalis\u00e9e qui r\u00e9pondra au mieux \u00e0 ses attentes. La demande \u00e9mise par ce formulaire ne sera donc pas ferme et d\u00e9finitive.<\/p>\n<h2>Informatique &amp; Libert\u00e9 :<\/h2>\n<p>Conform\u00e9ment \u00e0 la loi \u00ab\u00a0Informatique et Libert\u00e9s\u00a0\u00bb n\u00b0 78-17 du 6 janvier 1978 et \u00e0 ses changements intervenus le 6 ao\u00fbt 2004, relative \u00e0 l&rsquo;informatique, aux fichiers et aux libert\u00e9s, ce site a fait l&rsquo;objet d&rsquo;une d\u00e9claration \u00e0 la CNIL. Le traitement automatis\u00e9 des donn\u00e9es nominatives r\u00e9alis\u00e9es \u00e0 partir du site web www.aquatonic.fr\/rennes a fait de plus l&rsquo;objet d&rsquo;une d\u00e9claration aupr\u00e8s de la CNIL n\u00b0 XXXXX.<\/p>\n<h2>Informations personnelles &amp; confidentialit\u00e9 :<\/h2>\n<p>L&rsquo;utilisateur de ce site est notamment inform\u00e9 que, conform\u00e9ment \u00e0 l&rsquo;article 27 de la loi Informatique et Libert\u00e9s du 6 janvier 1978, les informations communiqu\u00e9es par l&rsquo;utilisateur du fait des formulaires pr\u00e9sents sur le site, sont n\u00e9cessaires pour r\u00e9pondre \u00e0 sa demande, et sont destin\u00e9es aux Thermes Marins de Saint Malo, responsable du traitement, \u00e0 des fins de gestion administrative et commerciale. Conform\u00e9ment \u00e0 l&rsquo;article 34 de la Loi Informatique et Libert\u00e9s, l&rsquo;utilisateur de ce site dispose d&rsquo;un droit d&rsquo;acc\u00e8s, de modification, de rectification et de suppression des donn\u00e9es qui le concernent. Pour exercer ce droit d&rsquo;acc\u00e8s, vous pouvez nous adresser votre demande aux Thermes Marins de Saint Malo dont les coordonn\u00e9es figurent ci-dessus. Pour plus d&rsquo;informations sur la loi Informatique et Libert\u00e9s, vous pouvez consulter le site Internet de la CNIL www.cnil.fr &#8211; Dossier n\u00b0 720259 d\u00e9clar\u00e9 par THERMES MARINS &#8211; Droit d&rsquo;acc\u00e8s aupr\u00e8s de RESERVATION CENTRALE GRANDE PLAGE DU SILLON BP32 35401 SAINT MALO CEDEX<\/p>\n<h2>Droits d&rsquo;auteurs :<\/h2>\n<p>Tout ce qui est contenu sur ce site web est prot\u00e9g\u00e9 par le droit d&rsquo;auteur. Toute reproduction ou repr\u00e9sentation tout ou partie, \u00e0 d&rsquo;autres fins sur un quelconque support est interdite sans l&rsquo;autorisation expresse et pr\u00e9alable de la Soci\u00e9t\u00e9 THERMES MARINS DE SAINT-MALO et constituerait une contrefa\u00e7on au sens des articles L 335-2 et suivants du code de la propri\u00e9t\u00e9 intellectuelle. La Soci\u00e9t\u00e9 THERMES MARINS DE SAINT-MALO ne donne aucune garantie sur les \u00e9l\u00e9ments pr\u00e9sents sur ce site qui sont fournis en l&rsquo;\u00e9tat et n&rsquo;assume aucune responsabilit\u00e9. La Soci\u00e9t\u00e9 THERMES MARINS DE SAINT-MALO n&rsquo;est pas responsable des erreurs ou omissions contenues sur ce site. De m\u00eame, la Soci\u00e9t\u00e9 THERMES MARINS DE SAINT-MALO n&rsquo;a aucun contr\u00f4le sur les liens hypertextes qui sont fournis uniquement \u00e0 titre de r\u00e9f\u00e9rence, elle d\u00e9cline donc toute responsabilit\u00e9 quant \u00e0 leur contenu.<br \/>\nL&rsquo;utilisateur s&rsquo;engage \u00e0 ne pas utiliser ce site Internet \u00e0 des fins interdites par la loi ou non autoris\u00e9es par les mentions l\u00e9gales<\/p>\n<h2>Protection des contenus &amp; cr\u00e9dits photographiques :<\/h2>\n<p>Cr\u00e9dits photos : Liste des photographes dont les photos ont \u00e9t\u00e9 utilis\u00e9es sur le site : S. Bourcier, M. Clauzier, C. Madamour, E. Margarita, JC. Valienne, B. Rebillard, B. Radvaner, F. Rambert, F. Pernisco, JM. Colleu, K. Bouetard, D. Girardon, X. Le Tinevez, B. Warion, M. Plassart, Croisi\u00e8re Pratique, C. Langlois, M. Erhardt, CUISINER, D. Torchut, JM. Tingaud, Lpg Systems, Images du Sud, P. Miara, MRW Zeppeline, B. Henry, J.F.Molliere, L. Bezard, JF Lefevre, C. Mac\u00e9, Iris L., R. Moleda, Capago, Easy Ride, E. Fleisher (Elan Hotel Pix), Flyoverhotel, C. Rodriguez, Helistar, Paul et Malo, Y. Werdefroy, Etoile marine, Surfschool, Thinkstock, Fotolia, Istock, Grand Aquarium, C. Rousseau, Le Studio, Canstockphoto, Shutterstock, Y.Briand, P. Helleu, Bellecour, Adhoc, Saint-Thomas TV, Booyasan, Gwern Image, Jean-Christophe Torres, Agence Captivate, Phototh\u00e8que TMSM.<\/p>\n<p>Ces photos ne sauraient faire l\u2019objet d\u2019une quelconque reproduction.<\/p>\n<h2>Marques &amp; Logos :<\/h2>\n<p>Les marques ou logos figurant sur ce site sont la propri\u00e9t\u00e9 des THERMES MARINS de Saint Malo ou sont exploit\u00e9s sous licence, ils ne peuvent donc \u00eatre utilis\u00e9s sans le consentement \u00e9crit pr\u00e9alable du propri\u00e9taire de la marque ou du logo sous peine de contrefa\u00e7on.<\/p>\n<h2 id=\"cookies\">Cookies :<\/h2>\n<p>Lors de la consultation de ce\u00a0site, des cookies sont d\u00e9pos\u00e9s sur votre ordinateur, votre mobile ou votre tablette par le serveur du site que vous visitez.<\/p>\n<p><strong>D\u00e9finition d\u2019un cookie<\/strong><\/p>\n<p>Un cookie (ou traceur) est un fichier texte d\u00e9pos\u00e9 sur votre ordinateur lors de la visite d\u2019un site ou de la consultation d\u2019une publicit\u00e9. Il a pour but de collecter des informations relatives \u00e0 votre navigation et de vous adresser des services adapt\u00e9s \u00e0 votre terminal (ordinateur, mobile ou tablette) et \u00e0 vos besoins. Les cookies sont g\u00e9r\u00e9s par votre navigateur internet.<\/p>\n<p>Les seuls cookies utilis\u00e9s par ce site ne permettent pas l\u2019identification, en revanche, ils enregistrent des informations relatives \u00e0 la navigation de l\u2019utilisateur sur le site. Les informations collect\u00e9es permettent de suivre le volume, le type et la configuration du trafic utilisant ce site afin d\u2019en d\u00e9velopper la conception et l\u2019agencement. Elles nous permettent \u00e9galement d\u2019am\u00e9liorer votre exp\u00e9rience client par l\u2019envoi d\u2019offres personnalis\u00e9es et en ad\u00e9quation avec vos besoins.<\/p>\n<p><strong>Param\u00e9trer votre navigateur internet<\/strong><\/p>\n<p>Il est possible de s\u2019opposer \u00e0 la collecte de vos informations de navigation en d\u00e9sactivant ces cookies. Votre navigateur peut \u00e9galement \u00eatre param\u00e9tr\u00e9 pour vous signaler les cookies qui sont d\u00e9pos\u00e9s dans votre ordinateur et vous demander de les accepter ou pas. Vous pouvez accepter ou refuser les cookies au cas par cas ou bien les refuser syst\u00e9matiquement.<\/p>\n<p>Afin de g\u00e9rer les cookies au plus pr\u00e8s de vos attentes nous vous invitons \u00e0 param\u00e9trer votre navigateur en tenant compte de la finalit\u00e9 des cookies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates actuellement connect\u00e9 au site aquatonic.fr\/rennes. L&rsquo;utilisateur ayant acc\u00e8s \u00e0 ce site s&rsquo;engage \u00e0 se conformer aux pr\u00e9sentes conditions d&rsquo;utilisation. Information \u00e9diteur et h\u00e9bergeur : Ce site est \u00e9dit\u00e9 par : LES THERMES MARINS DE SAINT MALO, Soci\u00e9t\u00e9 par actions simplifi\u00e9e au capital de 1 000 000 Euros, immatricul\u00e9e au Registre du Commerce et [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":29,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-104","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/pages\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":3,"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/pages\/104\/revisions"}],"predecessor-version":[{"id":115781,"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/pages\/104\/revisions\/115781"}],"wp:attachment":[{"href":"https:\/\/www.aquatonic.fr\/rennes\/wp-json\/wp\/v2\/media?parent=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}